{"id":797,"date":"2020-03-26T19:04:07","date_gmt":"2020-03-26T18:04:07","guid":{"rendered":"https:\/\/www.dieflieger.de\/records1\/wordpress\/?post_type=product&#038;p=797"},"modified":"2020-06-06T05:48:40","modified_gmt":"2020-06-06T03:48:40","slug":"alte-maedchen","status":"publish","type":"product","link":"https:\/\/www.dieflieger.de\/records1\/wordpress\/produkt\/alte-maedchen\/","title":{"rendered":"Alte M\u00e4dchen"},"content":{"rendered":"<p>Alte M\u00e4dchen<\/p>\n<p>1. Alte M\u00e4dchen Rap<\/p>\n<p>2. Heide Kabel<\/p>\n<p>3. Schlampe<\/p>\n<p>4. Doof<\/p>\n<p>5. Pauken und Trompeten<\/p>\n<p>6. Parship<\/p>\n<p>7. M\u00fcde Krieger<\/p>\n<p>8. B\u00fcstenhalter<\/p>\n<p>9. Angst ham<\/p>\n<p>10. Musical<\/p>\n<p>11. Anorektische Schw\u00e4ne<\/p>\n<p>12. Horrorkind<\/p>\n<p>13. Der sch\u00f6nste Busen der welt<\/p>\n<p>14. Bindegewebe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alte M\u00e4dchen<\/p>\n","protected":false},"featured_media":788,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[16],"product_tag":[],"class_list":{"0":"post-797","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cds","7":"product_shipping_class-allgemien","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.dieflieger.de\/records1\/wordpress\/wp-json\/wp\/v2\/product\/797"}],"collection":[{"href":"https:\/\/www.dieflieger.de\/records1\/wordpress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.dieflieger.de\/records1\/wordpress\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dieflieger.de\/records1\/wordpress\/wp-json\/wp\/v2\/comments?post=797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dieflieger.de\/records1\/wordpress\/wp-json\/wp\/v2\/media\/788"}],"wp:attachment":[{"href":"https:\/\/www.dieflieger.de\/records1\/wordpress\/wp-json\/wp\/v2\/media?parent=797"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.dieflieger.de\/records1\/wordpress\/wp-json\/wp\/v2\/product_cat?post=797"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.dieflieger.de\/records1\/wordpress\/wp-json\/wp\/v2\/product_tag?post=797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}